{"id":9985,"date":"2026-09-01T01:00:19","date_gmt":"2026-08-31T23:00:19","guid":{"rendered":"https:\/\/www.tourismus.dachau.de\/?post_type=events_heimatinfo&#038;p=9985"},"modified":"2026-09-02T01:00:15","modified_gmt":"2026-09-01T23:00:15","slug":"dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2","status":"publish","type":"events_heimatinfo","link":"https:\/\/www.tourismus.dachau.de\/en\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/","title":{"rendered":"Discovering Dachau (new) \u2013 Open old town tour with castle visit"},"content":{"rendered":"<p>Experience more than 1,200 years of Dachau history and stories on a guided walking tour through the historic old town. From its early beginnings through its time as a Wittelsbach summer residence and artists' colony, and the defining events of the National Socialist dictatorship to the present day.  <\/p>\n<p>A special highlight is the tour of Dachau Palace. Admission is already included in the participation fee. To conclude, participants can enjoy the panoramic view from the court garden across the Munich gravel plain to the Alps \u2013 weather permitting.<\/p>\n<p>The guided tour is equally suitable for locals, day-trippers, and vacationers, and is also an ideal complement to a visit to the Dachau Concentration Camp Memorial Site.<\/p>\n<p>Duration: approx. 2 hours<\/p>\n<p>Important note: To ensure the guided tour is a special and relaxed experience for all participants, the group size is intentionally limited. Please therefore register online in advance. This guarantees your spot and ensures you receive all important information conveniently before the tour.<\/p>\n<p>Relaxed, comfortable, register online directly at: https:\/\/stadtfuehrung-mit-matthias.de<\/p>\n<div><\/div>\n<div>Further dates: (Start 4 PM \/ End 6 PM)<\/div>\n<div>Thursday, August 6.<\/div>\n<div>Sunday, Aug 9.<\/div>\n<div><\/div>\n<div>Thursday, Aug 13.<\/div>\n<div>Friday, August 14.<\/div>\n<div>Saturday, Aug 15.<\/div>\n<div>Sunday, August 16.<\/div>\n<div><\/div>\n<div>Thursday, August 20.<\/div>\n<div>Friday, August 21.<\/div>\n<div>Saturday, Aug 22.<\/div>\n<div>Sunday, Aug 23.<\/div>\n<div><\/div>\n<div>Thursday, Aug 27.<\/div>\n<div>Friday, Aug 28.<\/div>\n<div>Saturday, August 29.<\/div>\n<div>Sunday, August 30.<\/div>\n<div><\/div>\n<div>Thursday, Sept. 17.<\/div>\n<div>Saturday, Sept 19.<\/div>\n<div><\/div>\n<div>Thursday, Sep 24.<\/div>\n<div>Friday, Sept. 25.<\/div>\n<div>Sunday, Sep 27.<\/div>\n<div><\/div>","protected":false},"excerpt":{"rendered":"<p>Erleben Sie mehr als 1.200 Jahre Dachauer Geschichte(n) bei einem gef\u00fchrten Rundgang durch die historische Altstadt. Von den fr\u00fchen Anf\u00e4ngen \u00fcber die Zeit als Wittelsbacher Sommerresidenz und K\u00fcnstlerkolonie zu den pr\u00e4genden Ereignissen der nationalsozialistischen Gewaltherrschaft bis in die Gegenwart. Ein besonderer H\u00f6hepunkt ist die Besichtigung des Dachauer Schlosses. Der Eintritt ist bereits im Teilnahmepreis enthalten. [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-9985","events_heimatinfo","type-events_heimatinfo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dachau (neu) entdecken \u2013 offene Altstadtf\u00fchrung mit Schlossbesichtigung - Dachau Tourismus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tourismus.dachau.de\/en\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dachau (neu) entdecken \u2013 offene Altstadtf\u00fchrung mit Schlossbesichtigung - Dachau Tourismus\" \/>\n<meta property=\"og:description\" content=\"Erleben Sie mehr als 1.200 Jahre Dachauer Geschichte(n) bei einem gef\u00fchrten Rundgang durch die historische Altstadt. Von den fr\u00fchen Anf\u00e4ngen \u00fcber die Zeit als Wittelsbacher Sommerresidenz und K\u00fcnstlerkolonie zu den pr\u00e4genden Ereignissen der nationalsozialistischen Gewaltherrschaft bis in die Gegenwart. Ein besonderer H\u00f6hepunkt ist die Besichtigung des Dachauer Schlosses. Der Eintritt ist bereits im Teilnahmepreis enthalten. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tourismus.dachau.de\/en\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dachau Tourismus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T23:00:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\\\/\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\\\/\",\"name\":\"Dachau (neu) entdecken \u2013 offene Altstadtf\u00fchrung mit Schlossbesichtigung - Dachau Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\"},\"datePublished\":\"2026-08-31T23:00:19+00:00\",\"dateModified\":\"2026-09-01T23:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dachau (neu) entdecken \u2013 offene Altstadtf\u00fchrung mit Schlossbesichtigung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"name\":\"Dachau Tourismus\",\"description\":\"Wir freuen uns \u00fcber Ihren Besuch auf unserer Website.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\",\"name\":\"Dachau Tourismus\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Dachau Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discovering Dachau (New) \u2013 Open Old Town Tour with Palace Visit - Dachau Tourism","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tourismus.dachau.de\/en\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/","og_locale":"en_US","og_type":"article","og_title":"Dachau (neu) entdecken \u2013 offene Altstadtf\u00fchrung mit Schlossbesichtigung - Dachau Tourismus","og_description":"Erleben Sie mehr als 1.200 Jahre Dachauer Geschichte(n) bei einem gef\u00fchrten Rundgang durch die historische Altstadt. Von den fr\u00fchen Anf\u00e4ngen \u00fcber die Zeit als Wittelsbacher Sommerresidenz und K\u00fcnstlerkolonie zu den pr\u00e4genden Ereignissen der nationalsozialistischen Gewaltherrschaft bis in die Gegenwart. Ein besonderer H\u00f6hepunkt ist die Besichtigung des Dachauer Schlosses. Der Eintritt ist bereits im Teilnahmepreis enthalten. [&hellip;]","og_url":"https:\/\/www.tourismus.dachau.de\/en\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/","og_site_name":"Dachau Tourismus","article_modified_time":"2026-09-01T23:00:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/","url":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/","name":"Discovering Dachau (New) \u2013 Open Old Town Tour with Palace Visit - Dachau Tourism","isPartOf":{"@id":"https:\/\/www.tourismus.dachau.de\/#website"},"datePublished":"2026-08-31T23:00:19+00:00","dateModified":"2026-09-01T23:00:15+00:00","breadcrumb":{"@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dachau-neu-entdecken-offene-altstadtfuehrung-mit-schlossbesichtigung-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tourismus.dachau.de\/"},{"@type":"ListItem","position":2,"name":"Dachau (neu) entdecken \u2013 offene Altstadtf\u00fchrung mit Schlossbesichtigung"}]},{"@type":"WebSite","@id":"https:\/\/www.tourismus.dachau.de\/#website","url":"https:\/\/www.tourismus.dachau.de\/","name":"Dachau Tourism","description":"We look forward to your visit to our website.","publisher":{"@id":"https:\/\/www.tourismus.dachau.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tourismus.dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tourismus.dachau.de\/#organization","name":"Dachau Tourism","url":"https:\/\/www.tourismus.dachau.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Dachau Tourismus"},"image":{"@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tourismus.dachau.de\/en\/wp-json\/wp\/v2\/events_heimatinfo\/9985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tourismus.dachau.de\/en\/wp-json\/wp\/v2\/events_heimatinfo"}],"about":[{"href":"https:\/\/www.tourismus.dachau.de\/en\/wp-json\/wp\/v2\/types\/events_heimatinfo"}],"wp:attachment":[{"href":"https:\/\/www.tourismus.dachau.de\/en\/wp-json\/wp\/v2\/media?parent=9985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}