{"id":9143,"date":"2026-07-14T01:00:12","date_gmt":"2026-07-13T23:00:12","guid":{"rendered":"https:\/\/www.tourismus.dachau.de\/?post_type=events_heimatinfo&#038;p=9143"},"modified":"2026-07-15T01:00:12","modified_gmt":"2026-07-14T23:00:12","slug":"dahdah-comedy-stand-up-comedy-open-mic-dachau","status":"publish","type":"events_heimatinfo","link":"https:\/\/www.tourismus.dachau.de\/fr\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/","title":{"rendered":"DahDah Comedy Stand-Up Comedy Open Mic Dachau"},"content":{"rendered":"<p>Die Stand-Up Comedy Open Mic Show in Dachau \u2013 Eintritt frei!<\/p>\n<p>Erlebe einen humorvollen Abend in entspannter Atmosph\u00e4re: Wir laden zur Stand-Up Comedy Open Mic Show in die Altstadt von Dachau ein \u2013 mit 6-8 Comedians und guter Laune garantiert!<\/p>\n<p>Was erwartet dich? Lokale und \u00fcberregionale Comedians testen neue Gags, teilen kuriose Anekdoten und bringen frischen Humor auf die B\u00fchne. Besonders spannend: Auch Newcomer feiern hier ihre ersten B\u00fchnenerfahrungen.<\/p>\n<p>Wir freuen uns auf dich! Egal ob Comedy-Fan oder einfach neugierig \u2013 komm vorbei, genie\u00dfe den Abend und unterst\u00fctze die lokale B\u00fchnenkultur. <\/p>\n<p>Einlass 18:30 Uhr, ab 16 Jahren. <\/p>\n<p>R\u00e9server des places en cliquant sur ce lien :<br \/>\nhttps:\/\/www.eventbrite.de\/e\/dahdah-comedy-stand-up-comedy-open-mic-dachau-tickets-1993646939664?aff=oddtdtcreator<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Stand-Up Comedy Open Mic Show in Dachau \u2013 Eintritt frei! Erlebe einen humorvollen Abend in entspannter Atmosph\u00e4re: Wir laden zur Stand-Up Comedy Open Mic Show in die Altstadt von Dachau ein \u2013 mit 6-8 Comedians und guter Laune garantiert! Was erwartet dich? Lokale und \u00fcberregionale Comedians testen neue Gags, teilen kuriose Anekdoten und bringen [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-9143","events_heimatinfo","type-events_heimatinfo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DahDah Comedy Stand-Up Comedy Open Mic Dachau - Dachau Tourismus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tourismus.dachau.de\/fr\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DahDah Comedy Stand-Up Comedy Open Mic Dachau - Dachau Tourismus\" \/>\n<meta property=\"og:description\" content=\"Die Stand-Up Comedy Open Mic Show in Dachau \u2013 Eintritt frei! Erlebe einen humorvollen Abend in entspannter Atmosph\u00e4re: Wir laden zur Stand-Up Comedy Open Mic Show in die Altstadt von Dachau ein \u2013 mit 6-8 Comedians und guter Laune garantiert! Was erwartet dich? Lokale und \u00fcberregionale Comedians testen neue Gags, teilen kuriose Anekdoten und bringen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tourismus.dachau.de\/fr\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/\" \/>\n<meta property=\"og:site_name\" content=\"Dachau Tourismus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T23:00:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dahdah-comedy-stand-up-comedy-open-mic-dachau\\\/\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dahdah-comedy-stand-up-comedy-open-mic-dachau\\\/\",\"name\":\"DahDah Comedy Stand-Up Comedy Open Mic Dachau - Dachau Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\"},\"datePublished\":\"2026-07-13T23:00:12+00:00\",\"dateModified\":\"2026-07-14T23:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dahdah-comedy-stand-up-comedy-open-mic-dachau\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dahdah-comedy-stand-up-comedy-open-mic-dachau\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/dahdah-comedy-stand-up-comedy-open-mic-dachau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DahDah Comedy Stand-Up Comedy Open Mic Dachau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"name\":\"Dachau Tourismus\",\"description\":\"Wir freuen uns \u00fcber Ihren Besuch auf unserer Website.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\",\"name\":\"Dachau Tourismus\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Dachau Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DahDah Comedy Stand-Up Comedy Open Mic Dachau - Dachau Tourismus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tourismus.dachau.de\/fr\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/","og_locale":"fr_FR","og_type":"article","og_title":"DahDah Comedy Stand-Up Comedy Open Mic Dachau - Dachau Tourismus","og_description":"Die Stand-Up Comedy Open Mic Show in Dachau \u2013 Eintritt frei! Erlebe einen humorvollen Abend in entspannter Atmosph\u00e4re: Wir laden zur Stand-Up Comedy Open Mic Show in die Altstadt von Dachau ein \u2013 mit 6-8 Comedians und guter Laune garantiert! Was erwartet dich? Lokale und \u00fcberregionale Comedians testen neue Gags, teilen kuriose Anekdoten und bringen [&hellip;]","og_url":"https:\/\/www.tourismus.dachau.de\/fr\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/","og_site_name":"Dachau Tourismus","article_modified_time":"2026-07-14T23:00:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/","url":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/","name":"DahDah Comedy Stand-Up Comedy Open Mic Dachau - Dachau Tourismus","isPartOf":{"@id":"https:\/\/www.tourismus.dachau.de\/#website"},"datePublished":"2026-07-13T23:00:12+00:00","dateModified":"2026-07-14T23:00:12+00:00","breadcrumb":{"@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/dahdah-comedy-stand-up-comedy-open-mic-dachau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tourismus.dachau.de\/"},{"@type":"ListItem","position":2,"name":"DahDah Comedy Stand-Up Comedy Open Mic Dachau"}]},{"@type":"WebSite","@id":"https:\/\/www.tourismus.dachau.de\/#website","url":"https:\/\/www.tourismus.dachau.de\/","name":"Tourisme de Dachau","description":"Nous nous r\u00e9jouissons de votre visite sur notre site web.","publisher":{"@id":"https:\/\/www.tourismus.dachau.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tourismus.dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.tourismus.dachau.de\/#organization","name":"Tourisme de Dachau","url":"https:\/\/www.tourismus.dachau.de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Dachau Tourismus"},"image":{"@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tourismus.dachau.de\/fr\/wp-json\/wp\/v2\/events_heimatinfo\/9143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tourismus.dachau.de\/fr\/wp-json\/wp\/v2\/events_heimatinfo"}],"about":[{"href":"https:\/\/www.tourismus.dachau.de\/fr\/wp-json\/wp\/v2\/types\/events_heimatinfo"}],"wp:attachment":[{"href":"https:\/\/www.tourismus.dachau.de\/fr\/wp-json\/wp\/v2\/media?parent=9143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}