{"id":5192,"date":"2026-09-01T01:00:19","date_gmt":"2026-08-31T23:00:19","guid":{"rendered":"https:\/\/www.tourismus.dachau.de\/?post_type=events_heimatinfo&#038;p=5192"},"modified":"2026-09-02T01:00:15","modified_gmt":"2026-09-01T23:00:15","slug":"fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3","status":"publish","type":"events_heimatinfo","link":"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/","title":{"rendered":"Visita guidata alla mostra speciale \u201eSENSI - Sulla storia culturale della nostra percezione\u201c"},"content":{"rendered":"<p>Visite guidate della mostra speciale \u201eSENSI - Sulla storia culturale della nostra percezione\u201c<br \/>\nI nostri tour pubblici offrono un accesso vivace ai cinque sensi e alla loro storia culturale. Insieme esploreremo come vista, udito, olfatto, gusto e tatto plasmano la nostra vita quotidiana e come sorprendentemente le persone percepivano il mondo in passato.<\/p>\n<p>Registrazione richiesta: Tel. 08131 5675-13 o verwaltung@dachauer-galerien-museen.de<\/p>\n<p>(4 \u20ac di spese di gestione, pi\u00f9 ingresso)<\/p>","protected":false},"excerpt":{"rendered":"<p>Gef\u00fchrte Rundg\u00e4nge durch die Sonderausstellung &#8222;SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung&#8220; Unsere \u00f6ffentlichen F\u00fchrungen bieten einen lebendigen Zugang zu den f\u00fcnf Sinnen und ihrer Kulturgeschichte. Gemeinsam erkunden wir, wie Sehen, H\u00f6ren, Riechen, Schmecken und Tasten unseren Alltag pr\u00e4gen und wie \u00fcberraschend anders Menschen fr\u00fcher wahrgenommen haben. Anmeldung erforderlich: Tel. 08131 5675\u201113 oder verwaltung@dachauer-galerien-museen.de (4 \u20ac [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-5192","events_heimatinfo","type-events_heimatinfo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00fchrung durch die Sonderausstellung &quot;SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung&quot; - Dachau Tourismus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fchrung durch die Sonderausstellung &quot;SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung&quot; - Dachau Tourismus\" \/>\n<meta property=\"og:description\" content=\"Gef\u00fchrte Rundg\u00e4nge durch die Sonderausstellung &#8222;SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung&#8220; Unsere \u00f6ffentlichen F\u00fchrungen bieten einen lebendigen Zugang zu den f\u00fcnf Sinnen und ihrer Kulturgeschichte. Gemeinsam erkunden wir, wie Sehen, H\u00f6ren, Riechen, Schmecken und Tasten unseren Alltag pr\u00e4gen und wie \u00fcberraschend anders Menschen fr\u00fcher wahrgenommen haben. Anmeldung erforderlich: Tel. 08131 5675\u201113 oder verwaltung@dachauer-galerien-museen.de (4 \u20ac [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Dachau Tourismus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T23:00:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\\\/\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\\\/\",\"name\":\"F\u00fchrung durch die Sonderausstellung \\\"SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung\\\" - Dachau Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\"},\"datePublished\":\"2026-08-31T23:00:19+00:00\",\"dateModified\":\"2026-09-01T23:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00fchrung durch die Sonderausstellung &#8222;SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"name\":\"Dachau Tourismus\",\"description\":\"Wir freuen uns \u00fcber Ihren Besuch auf unserer Website.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\",\"name\":\"Dachau Tourismus\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Dachau Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fchrung durch die Sonderausstellung \"SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung\" - Dachau Tourismus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/","og_locale":"it_IT","og_type":"article","og_title":"F\u00fchrung durch die Sonderausstellung \"SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung\" - Dachau Tourismus","og_description":"Gef\u00fchrte Rundg\u00e4nge durch die Sonderausstellung &#8222;SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung&#8220; Unsere \u00f6ffentlichen F\u00fchrungen bieten einen lebendigen Zugang zu den f\u00fcnf Sinnen und ihrer Kulturgeschichte. Gemeinsam erkunden wir, wie Sehen, H\u00f6ren, Riechen, Schmecken und Tasten unseren Alltag pr\u00e4gen und wie \u00fcberraschend anders Menschen fr\u00fcher wahrgenommen haben. Anmeldung erforderlich: Tel. 08131 5675\u201113 oder verwaltung@dachauer-galerien-museen.de (4 \u20ac [&hellip;]","og_url":"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/","og_site_name":"Dachau Tourismus","article_modified_time":"2026-09-01T23:00:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/","url":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/","name":"F\u00fchrung durch die Sonderausstellung \"SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung\" - Dachau Tourismus","isPartOf":{"@id":"https:\/\/www.tourismus.dachau.de\/#website"},"datePublished":"2026-08-31T23:00:19+00:00","dateModified":"2026-09-01T23:00:15+00:00","breadcrumb":{"@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fuehrung-durch-die-sonderausstellung-sinne-zur-kulturgeschichte-unserer-wahrnehmung-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tourismus.dachau.de\/"},{"@type":"ListItem","position":2,"name":"F\u00fchrung durch die Sonderausstellung &#8222;SINNE \u2013 Zur Kulturgeschichte unserer Wahrnehmung&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/www.tourismus.dachau.de\/#website","url":"https:\/\/www.tourismus.dachau.de\/","name":"Turismo a Dachau","description":"Vi aspettiamo per una visita al nostro sito web.","publisher":{"@id":"https:\/\/www.tourismus.dachau.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tourismus.dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tourismus.dachau.de\/#organization","name":"Turismo a Dachau","url":"https:\/\/www.tourismus.dachau.de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Dachau Tourismus"},"image":{"@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tourismus.dachau.de\/it\/wp-json\/wp\/v2\/events_heimatinfo\/5192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tourismus.dachau.de\/it\/wp-json\/wp\/v2\/events_heimatinfo"}],"about":[{"href":"https:\/\/www.tourismus.dachau.de\/it\/wp-json\/wp\/v2\/types\/events_heimatinfo"}],"wp:attachment":[{"href":"https:\/\/www.tourismus.dachau.de\/it\/wp-json\/wp\/v2\/media?parent=5192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}