{"id":9170,"date":"2026-07-14T01:00:12","date_gmt":"2026-07-13T23:00:12","guid":{"rendered":"https:\/\/www.tourismus.dachau.de\/?post_type=events_heimatinfo&#038;p=9170"},"modified":"2026-07-15T01:00:12","modified_gmt":"2026-07-14T23:00:12","slug":"ganes-best-of-ganes","status":"publish","type":"events_heimatinfo","link":"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/ganes-best-of-ganes\/","title":{"rendered":"Ganes \u2013 Best of Ganes"},"content":{"rendered":"<p>Nach der erfolgreichen \u201eVives!\u201c-Tour pr\u00e4sentieren die drei ladinischen Musikerinnen von GANES auf ihrer exklusiven Best-of-Tour Lieblingssongs aus allen Alben. Mehrstimmiger Gesang, fetzige Streicherpassagen der Schuen-Schwestern, grooviger Sound von der Kontrabassistin Natalie Pl\u00f6ger und virtuose Gitarrensoli von Raffael Holzhauser verschmelzen zu ihrem unverwechselbaren Sound. Dazu erz\u00e4hlen GANES humorvolle Geschichten aus \u00fcber 15 Jahren Bandgeschichte. Ein Konzertabend voller Energie, Charme und musikalischer Vielfalt.<\/p>\n<p>Eintritt: 25 \u20ac, erm\u00e4\u00dfigt: 23 \u20ac<\/p>\n<p>Ingresso: 19:30<\/p>\n<p>Vorverkauf:<br \/>\nNaturkostinsel in der M\u00fcnchner Str. 52, Dachau oder \u00fcber den Ticket Online-Verkauf: ticketino.com<\/p>\n<p>Contatto:<br \/>\nKleinkunstb\u00fchne Leierkasten Dachau<br \/>\nUhdestr. 2, 85221<\/p>\n<p>Telefon: 08131 \u2013 55195<br \/>\nE-Mail: info@leierkasten-dachau.de<br \/>\nHomepage: www.leierkasten-dachau.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Nach der erfolgreichen \u201eVives!\u201c-Tour pr\u00e4sentieren die drei ladinischen Musikerinnen von GANES auf ihrer exklusiven Best-of-Tour Lieblingssongs aus allen Alben. Mehrstimmiger Gesang, fetzige Streicherpassagen der Schuen-Schwestern, grooviger Sound von der Kontrabassistin Natalie Pl\u00f6ger und virtuose Gitarrensoli von Raffael Holzhauser verschmelzen zu ihrem unverwechselbaren Sound. Dazu erz\u00e4hlen GANES humorvolle Geschichten aus \u00fcber 15 Jahren Bandgeschichte. Ein Konzertabend [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-9170","events_heimatinfo","type-events_heimatinfo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ganes \u2013 Best of Ganes - Dachau Tourismus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/ganes-best-of-ganes\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ganes \u2013 Best of Ganes - Dachau Tourismus\" \/>\n<meta property=\"og:description\" content=\"Nach der erfolgreichen \u201eVives!\u201c-Tour pr\u00e4sentieren die drei ladinischen Musikerinnen von GANES auf ihrer exklusiven Best-of-Tour Lieblingssongs aus allen Alben. Mehrstimmiger Gesang, fetzige Streicherpassagen der Schuen-Schwestern, grooviger Sound von der Kontrabassistin Natalie Pl\u00f6ger und virtuose Gitarrensoli von Raffael Holzhauser verschmelzen zu ihrem unverwechselbaren Sound. Dazu erz\u00e4hlen GANES humorvolle Geschichten aus \u00fcber 15 Jahren Bandgeschichte. Ein Konzertabend [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/ganes-best-of-ganes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dachau Tourismus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T23:00:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/ganes-best-of-ganes\\\/\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/ganes-best-of-ganes\\\/\",\"name\":\"Ganes \u2013 Best of Ganes - Dachau Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\"},\"datePublished\":\"2026-07-13T23:00:12+00:00\",\"dateModified\":\"2026-07-14T23:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/ganes-best-of-ganes\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/ganes-best-of-ganes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/ganes-best-of-ganes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ganes \u2013 Best of Ganes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"name\":\"Dachau Tourismus\",\"description\":\"Wir freuen uns \u00fcber Ihren Besuch auf unserer Website.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\",\"name\":\"Dachau Tourismus\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Dachau Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ganes \u2013 Best of Ganes - Dachau Tourismus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/ganes-best-of-ganes\/","og_locale":"it_IT","og_type":"article","og_title":"Ganes \u2013 Best of Ganes - Dachau Tourismus","og_description":"Nach der erfolgreichen \u201eVives!\u201c-Tour pr\u00e4sentieren die drei ladinischen Musikerinnen von GANES auf ihrer exklusiven Best-of-Tour Lieblingssongs aus allen Alben. Mehrstimmiger Gesang, fetzige Streicherpassagen der Schuen-Schwestern, grooviger Sound von der Kontrabassistin Natalie Pl\u00f6ger und virtuose Gitarrensoli von Raffael Holzhauser verschmelzen zu ihrem unverwechselbaren Sound. Dazu erz\u00e4hlen GANES humorvolle Geschichten aus \u00fcber 15 Jahren Bandgeschichte. Ein Konzertabend [&hellip;]","og_url":"https:\/\/www.tourismus.dachau.de\/it\/veranstaltungskalender\/ganes-best-of-ganes\/","og_site_name":"Dachau Tourismus","article_modified_time":"2026-07-14T23:00:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/ganes-best-of-ganes\/","url":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/ganes-best-of-ganes\/","name":"Ganes \u2013 Best of Ganes - Dachau Tourismus","isPartOf":{"@id":"https:\/\/www.tourismus.dachau.de\/#website"},"datePublished":"2026-07-13T23:00:12+00:00","dateModified":"2026-07-14T23:00:12+00:00","breadcrumb":{"@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/ganes-best-of-ganes\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/ganes-best-of-ganes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/ganes-best-of-ganes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tourismus.dachau.de\/"},{"@type":"ListItem","position":2,"name":"Ganes \u2013 Best of Ganes"}]},{"@type":"WebSite","@id":"https:\/\/www.tourismus.dachau.de\/#website","url":"https:\/\/www.tourismus.dachau.de\/","name":"Turismo a Dachau","description":"Vi aspettiamo per una visita al nostro sito web.","publisher":{"@id":"https:\/\/www.tourismus.dachau.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tourismus.dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tourismus.dachau.de\/#organization","name":"Turismo a Dachau","url":"https:\/\/www.tourismus.dachau.de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Dachau Tourismus"},"image":{"@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tourismus.dachau.de\/it\/wp-json\/wp\/v2\/events_heimatinfo\/9170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tourismus.dachau.de\/it\/wp-json\/wp\/v2\/events_heimatinfo"}],"about":[{"href":"https:\/\/www.tourismus.dachau.de\/it\/wp-json\/wp\/v2\/types\/events_heimatinfo"}],"wp:attachment":[{"href":"https:\/\/www.tourismus.dachau.de\/it\/wp-json\/wp\/v2\/media?parent=9170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}