{"id":12028,"date":"2026-08-28T01:00:39","date_gmt":"2026-08-27T23:00:39","guid":{"rendered":"https:\/\/www.tourismus.dachau.de\/?post_type=events_heimatinfo&#038;p=12028"},"modified":"2026-09-02T01:00:13","modified_gmt":"2026-09-01T23:00:13","slug":"fluonight-2026-glow-in-the-dark","status":"publish","type":"events_heimatinfo","link":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/","title":{"rendered":"Fluonight 2026 &#8211; Glow in the dark"},"content":{"rendered":"<p>Am Freitag, 20. November 2026, wird es in der NaturFreunde Kletterhalle Dachau wieder bunt: Bei der FLUO NIGHT 2026 verwandeln Schwarzlicht, Neonfarben und fluoreszierende Klettergriffe die Halle in eine leuchtende Kletterwelt. Mit Stirnlampe, Neon-Outfit und entspannten Beats wird geklettert und gebouldert \u2013 ganz ohne Wettkampf, daf\u00fcr mit besonderer Atmosph\u00e4re.<\/p>\n<p>Mit dabei ist auch die Alpinschule Augsburg mit ihrem mobilen Kraftmesssystem. Besucherinnen und Besucher k\u00f6nnen ihre kletterspezifische Kraft testen und erhalten Tipps f\u00fcr ihr pers\u00f6nliches Training.<\/p>\n<p>Veranstalter: NaturFreunde Kletterhalle Dachau<br \/>\nTermin: Freitag, 20. November 2026<br \/>\nOrt: Wettersteinring 14, 85221 Dachau<br \/>\nKosten: regul\u00e4rer Halleneintritt<br \/>\nKontakt: post@kletterhalle-dachau.de | Tel. 08131 3377577<br \/>\nWeitere Informationen &amp; Anmeldung: kletterhalle-dachau.de\/events\/fluo-night-2026-es-wird-wieder-bunt<\/p>","protected":false},"excerpt":{"rendered":"<p>Am Freitag, 20. November 2026, wird es in der NaturFreunde Kletterhalle Dachau wieder bunt: Bei der FLUO NIGHT 2026 verwandeln Schwarzlicht, Neonfarben und fluoreszierende Klettergriffe die Halle in eine leuchtende Kletterwelt. Mit Stirnlampe, Neon-Outfit und entspannten Beats wird geklettert und gebouldert \u2013 ganz ohne Wettkampf, daf\u00fcr mit besonderer Atmosph\u00e4re. Mit dabei ist auch die Alpinschule [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-12028","events_heimatinfo","type-events_heimatinfo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fluonight 2026 - Glow in the dark - Dachau Tourismus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fluonight 2026 - Glow in the dark - Dachau Tourismus\" \/>\n<meta property=\"og:description\" content=\"Am Freitag, 20. November 2026, wird es in der NaturFreunde Kletterhalle Dachau wieder bunt: Bei der FLUO NIGHT 2026 verwandeln Schwarzlicht, Neonfarben und fluoreszierende Klettergriffe die Halle in eine leuchtende Kletterwelt. Mit Stirnlampe, Neon-Outfit und entspannten Beats wird geklettert und gebouldert \u2013 ganz ohne Wettkampf, daf\u00fcr mit besonderer Atmosph\u00e4re. Mit dabei ist auch die Alpinschule [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/\" \/>\n<meta property=\"og:site_name\" content=\"Dachau Tourismus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T23:00:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fluonight-2026-glow-in-the-dark\\\/\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fluonight-2026-glow-in-the-dark\\\/\",\"name\":\"Fluonight 2026 - Glow in the dark - Dachau Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\"},\"datePublished\":\"2026-08-27T23:00:39+00:00\",\"dateModified\":\"2026-09-01T23:00:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fluonight-2026-glow-in-the-dark\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fluonight-2026-glow-in-the-dark\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/fluonight-2026-glow-in-the-dark\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fluonight 2026 &#8211; Glow in the dark\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"name\":\"Dachau Tourismus\",\"description\":\"Wir freuen uns \u00fcber Ihren Besuch auf unserer Website.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\",\"name\":\"Dachau Tourismus\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Dachau Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fluonight 2026 - Glow in the dark - Dachau Tourismus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/","og_locale":"pl_PL","og_type":"article","og_title":"Fluonight 2026 - Glow in the dark - Dachau Tourismus","og_description":"Am Freitag, 20. November 2026, wird es in der NaturFreunde Kletterhalle Dachau wieder bunt: Bei der FLUO NIGHT 2026 verwandeln Schwarzlicht, Neonfarben und fluoreszierende Klettergriffe die Halle in eine leuchtende Kletterwelt. Mit Stirnlampe, Neon-Outfit und entspannten Beats wird geklettert und gebouldert \u2013 ganz ohne Wettkampf, daf\u00fcr mit besonderer Atmosph\u00e4re. Mit dabei ist auch die Alpinschule [&hellip;]","og_url":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/","og_site_name":"Dachau Tourismus","article_modified_time":"2026-09-01T23:00:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/","url":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/","name":"Fluonight 2026 - Glow in the dark - Dachau Tourismus","isPartOf":{"@id":"https:\/\/www.tourismus.dachau.de\/#website"},"datePublished":"2026-08-27T23:00:39+00:00","dateModified":"2026-09-01T23:00:13+00:00","breadcrumb":{"@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/fluonight-2026-glow-in-the-dark\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tourismus.dachau.de\/"},{"@type":"ListItem","position":2,"name":"Fluonight 2026 &#8211; Glow in the dark"}]},{"@type":"WebSite","@id":"https:\/\/www.tourismus.dachau.de\/#website","url":"https:\/\/www.tourismus.dachau.de\/","name":"Turystyka w Dachau","description":"Z niecierpliwo\u015bci\u0105 czekamy na Twoj\u0105 wizyt\u0119 na naszej stronie.","publisher":{"@id":"https:\/\/www.tourismus.dachau.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tourismus.dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.tourismus.dachau.de\/#organization","name":"Turystyka w Dachau","url":"https:\/\/www.tourismus.dachau.de\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Dachau Tourismus"},"image":{"@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/events_heimatinfo\/12028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/events_heimatinfo"}],"about":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/types\/events_heimatinfo"}],"wp:attachment":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/media?parent=12028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}