{"id":5189,"date":"2026-09-01T01:00:19","date_gmt":"2026-08-31T23:00:19","guid":{"rendered":"https:\/\/www.tourismus.dachau.de\/?post_type=events_heimatinfo&#038;p=5189"},"modified":"2026-09-02T01:00:15","modified_gmt":"2026-09-01T23:00:15","slug":"abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung","status":"publish","type":"events_heimatinfo","link":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/","title":{"rendered":"Wieczorne oprowadzanie z kuratork\u0105 Ursul\u0105 Nauderer | ZMYS\u0141Y \u2013 Do historii kultury postrzegania"},"content":{"rendered":"<p>Muzeum Okr\u0119gowe w Dachau zaprasza na specjalne zwiedzanie wieczorne: kuratorka Ursula Nauderer zabierze nas za kulisy wystawy \"zmys\u0142y\" i opowie, jak postrzeganie, materia\u0142 i atmosfera wsp\u00f3\u0142dzia\u0142aj\u0105. Inspiruj\u0105ca w\u0119dr\u00f3wka, kt\u00f3ra sprawia, \u017ce sztuka staje si\u0119 namacalna.<\/p>\n<p>Koszty: 14 \u20ac w\u0142\u0105cznie z wej\u015bciem, przewodnikiem i napojem<\/p>\n<p>Wymagane zg\u0142oszenie: Tel. 08131 5675\u201113 lub verwaltung@dachauer-galerien-museen.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Bezirksmuseum Dachau l\u00e4dt zu einer besonderen Abendf\u00fchrung ein: Kuratorin Ursula Nauderer \u00f6ffnet den Blick hinter die Kulissen der Ausstellung sinne und erz\u00e4hlt, wie Wahrnehmung, Material und Atmosph\u00e4re hier zusammenspielen. Ein inspirierender Rundgang, der Kunst sp\u00fcrbar macht. Kosten: 14 \u20ac inkl. Eintritt, F\u00fchrung &amp; Drink Anmeldung erforderlich: Tel. 08131 5675\u201113 oder verwaltung@dachauer-galerien-museen.de<\/p>","protected":false},"featured_media":0,"template":"","class_list":["post-5189","events_heimatinfo","type-events_heimatinfo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abendf\u00fchrung mit der Kuratorin Ursula Nauderer | SINNE - Zur Kulturgeschichte unserer Wahrnehmung - Dachau Tourismus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abendf\u00fchrung mit der Kuratorin Ursula Nauderer | SINNE - Zur Kulturgeschichte unserer Wahrnehmung - Dachau Tourismus\" \/>\n<meta property=\"og:description\" content=\"Das Bezirksmuseum Dachau l\u00e4dt zu einer besonderen Abendf\u00fchrung ein: Kuratorin Ursula Nauderer \u00f6ffnet den Blick hinter die Kulissen der Ausstellung sinne und erz\u00e4hlt, wie Wahrnehmung, Material und Atmosph\u00e4re hier zusammenspielen. Ein inspirierender Rundgang, der Kunst sp\u00fcrbar macht. Kosten: 14 \u20ac inkl. Eintritt, F\u00fchrung &amp; Drink Anmeldung erforderlich: Tel. 08131 5675\u201113 oder verwaltung@dachauer-galerien-museen.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/\" \/>\n<meta property=\"og:site_name\" content=\"Dachau Tourismus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T23:00:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\\\/\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\\\/\",\"name\":\"Abendf\u00fchrung mit der Kuratorin Ursula Nauderer | SINNE - Zur Kulturgeschichte unserer Wahrnehmung - Dachau Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\"},\"datePublished\":\"2026-08-31T23:00:19+00:00\",\"dateModified\":\"2026-09-01T23:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abendf\u00fchrung mit der Kuratorin Ursula Nauderer | SINNE &#8211; Zur Kulturgeschichte unserer Wahrnehmung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"name\":\"Dachau Tourismus\",\"description\":\"Wir freuen uns \u00fcber Ihren Besuch auf unserer Website.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\",\"name\":\"Dachau Tourismus\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Dachau Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abendf\u00fchrung mit der Kuratorin Ursula Nauderer | SINNE - Zur Kulturgeschichte unserer Wahrnehmung - Dachau Tourismus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/","og_locale":"pl_PL","og_type":"article","og_title":"Abendf\u00fchrung mit der Kuratorin Ursula Nauderer | SINNE - Zur Kulturgeschichte unserer Wahrnehmung - Dachau Tourismus","og_description":"Das Bezirksmuseum Dachau l\u00e4dt zu einer besonderen Abendf\u00fchrung ein: Kuratorin Ursula Nauderer \u00f6ffnet den Blick hinter die Kulissen der Ausstellung sinne und erz\u00e4hlt, wie Wahrnehmung, Material und Atmosph\u00e4re hier zusammenspielen. Ein inspirierender Rundgang, der Kunst sp\u00fcrbar macht. Kosten: 14 \u20ac inkl. Eintritt, F\u00fchrung &amp; Drink Anmeldung erforderlich: Tel. 08131 5675\u201113 oder verwaltung@dachauer-galerien-museen.de","og_url":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/","og_site_name":"Dachau Tourismus","article_modified_time":"2026-09-01T23:00:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/","url":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/","name":"Abendf\u00fchrung mit der Kuratorin Ursula Nauderer | SINNE - Zur Kulturgeschichte unserer Wahrnehmung - Dachau Tourismus","isPartOf":{"@id":"https:\/\/www.tourismus.dachau.de\/#website"},"datePublished":"2026-08-31T23:00:19+00:00","dateModified":"2026-09-01T23:00:15+00:00","breadcrumb":{"@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/abendfuehrung-mit-der-kuratorin-ursula-nauderer-sinne-zur-kulturgeschichte-unserer-wahrnehmung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tourismus.dachau.de\/"},{"@type":"ListItem","position":2,"name":"Abendf\u00fchrung mit der Kuratorin Ursula Nauderer | SINNE &#8211; Zur Kulturgeschichte unserer Wahrnehmung"}]},{"@type":"WebSite","@id":"https:\/\/www.tourismus.dachau.de\/#website","url":"https:\/\/www.tourismus.dachau.de\/","name":"Turystyka w Dachau","description":"Z niecierpliwo\u015bci\u0105 czekamy na Twoj\u0105 wizyt\u0119 na naszej stronie.","publisher":{"@id":"https:\/\/www.tourismus.dachau.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tourismus.dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.tourismus.dachau.de\/#organization","name":"Turystyka w Dachau","url":"https:\/\/www.tourismus.dachau.de\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Dachau Tourismus"},"image":{"@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/events_heimatinfo\/5189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/events_heimatinfo"}],"about":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/types\/events_heimatinfo"}],"wp:attachment":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/media?parent=5189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}