{"id":9174,"date":"2026-07-14T01:00:11","date_gmt":"2026-07-13T23:00:11","guid":{"rendered":"https:\/\/www.tourismus.dachau.de\/?post_type=events_heimatinfo&#038;p=9174"},"modified":"2026-07-15T01:00:12","modified_gmt":"2026-07-14T23:00:12","slug":"edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee","status":"publish","type":"events_heimatinfo","link":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/","title":{"rendered":"Edgar unterwegs nach Weihnachten &#8211; Figurentheater Hattenkofer\/Prien a. Chiemsee"},"content":{"rendered":"<p>&#8222;Ich will auch Weihnachten feiern&#8220;, beschlie\u00dft Edgar die Wildgans, und zieht daher nicht mit den anderen G\u00e4nsen in den S\u00fcden. Er bleibt lieber hier, um auf Weihnachten zu warten. Die lange Zeit bis dahin zu \u00fcberstehen ist nicht einfach f\u00fcr die kleine Gans. Noch dazu, wo er K\u00e4lte, Schnee und Eis gar nicht kennt und all die anderen Tiere mit den Vorbereitungen f\u00fcr den Winterschlaf besch\u00e4ftigt sind. Au\u00dfer Edgar scheint sich auch niemand f\u00fcr Weihnachten zu interessieren, oder doch?<\/p>\n<p>Karten \u2013 Kinder \/ Erwachsene: 7 \u20ac<\/p>\n<p>Einlass: 15:20, Dauer: 45 min.<\/p>\n<p>Alter: Kinder ab 4 Jahren<\/p>\n<p>Vorverkauf:  Naturkostinsel in der M\u00fcnchner Str. 52, Dachau oder \u00fcber den Ticket Online-Verkauf: ticketino.com<\/p>\n<p>Kontakt:<br \/>\nKleinkunstb\u00fchne Leierkasten Dachau<br \/>\nUhdestr. 2, 85221<\/p>\n<p>Telefon: 08131 \u2013 55195<br \/>\nE-Mail: info@leierkasten-dachau.de<br \/>\nHomepage: www.leierkasten-dachau.de<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8222;Ich will auch Weihnachten feiern&#8220;, beschlie\u00dft Edgar die Wildgans, und zieht daher nicht mit den anderen G\u00e4nsen in den S\u00fcden. Er bleibt lieber hier, um auf Weihnachten zu warten. Die lange Zeit bis dahin zu \u00fcberstehen ist nicht einfach f\u00fcr die kleine Gans. Noch dazu, wo er K\u00e4lte, Schnee und Eis gar nicht kennt und [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-9174","events_heimatinfo","type-events_heimatinfo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edgar unterwegs nach Weihnachten - Figurentheater Hattenkofer\/Prien a. Chiemsee - Dachau Tourismus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edgar unterwegs nach Weihnachten - Figurentheater Hattenkofer\/Prien a. Chiemsee - Dachau Tourismus\" \/>\n<meta property=\"og:description\" content=\"&#8222;Ich will auch Weihnachten feiern&#8220;, beschlie\u00dft Edgar die Wildgans, und zieht daher nicht mit den anderen G\u00e4nsen in den S\u00fcden. Er bleibt lieber hier, um auf Weihnachten zu warten. Die lange Zeit bis dahin zu \u00fcberstehen ist nicht einfach f\u00fcr die kleine Gans. Noch dazu, wo er K\u00e4lte, Schnee und Eis gar nicht kennt und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dachau Tourismus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T23:00:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\\\/\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\\\/\",\"name\":\"Edgar unterwegs nach Weihnachten - Figurentheater Hattenkofer\\\/Prien a. Chiemsee - Dachau Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\"},\"datePublished\":\"2026-07-13T23:00:11+00:00\",\"dateModified\":\"2026-07-14T23:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edgar unterwegs nach Weihnachten &#8211; Figurentheater Hattenkofer\\\/Prien a. Chiemsee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"name\":\"Dachau Tourismus\",\"description\":\"Wir freuen uns \u00fcber Ihren Besuch auf unserer Website.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\",\"name\":\"Dachau Tourismus\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Dachau Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edgar unterwegs nach Weihnachten - Figurentheater Hattenkofer\/Prien a. Chiemsee - Dachau Tourismus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/","og_locale":"pl_PL","og_type":"article","og_title":"Edgar unterwegs nach Weihnachten - Figurentheater Hattenkofer\/Prien a. Chiemsee - Dachau Tourismus","og_description":"&#8222;Ich will auch Weihnachten feiern&#8220;, beschlie\u00dft Edgar die Wildgans, und zieht daher nicht mit den anderen G\u00e4nsen in den S\u00fcden. Er bleibt lieber hier, um auf Weihnachten zu warten. Die lange Zeit bis dahin zu \u00fcberstehen ist nicht einfach f\u00fcr die kleine Gans. Noch dazu, wo er K\u00e4lte, Schnee und Eis gar nicht kennt und [&hellip;]","og_url":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/","og_site_name":"Dachau Tourismus","article_modified_time":"2026-07-14T23:00:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/","url":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/","name":"Edgar unterwegs nach Weihnachten - Figurentheater Hattenkofer\/Prien a. Chiemsee - Dachau Tourismus","isPartOf":{"@id":"https:\/\/www.tourismus.dachau.de\/#website"},"datePublished":"2026-07-13T23:00:11+00:00","dateModified":"2026-07-14T23:00:12+00:00","breadcrumb":{"@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/edgar-unterwegs-nach-weihnachten-figurentheater-hattenkofer-prien-a-chiemsee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tourismus.dachau.de\/"},{"@type":"ListItem","position":2,"name":"Edgar unterwegs nach Weihnachten &#8211; Figurentheater Hattenkofer\/Prien a. Chiemsee"}]},{"@type":"WebSite","@id":"https:\/\/www.tourismus.dachau.de\/#website","url":"https:\/\/www.tourismus.dachau.de\/","name":"Turystyka w Dachau","description":"Z niecierpliwo\u015bci\u0105 czekamy na Twoj\u0105 wizyt\u0119 na naszej stronie.","publisher":{"@id":"https:\/\/www.tourismus.dachau.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tourismus.dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.tourismus.dachau.de\/#organization","name":"Turystyka w Dachau","url":"https:\/\/www.tourismus.dachau.de\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Dachau Tourismus"},"image":{"@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/events_heimatinfo\/9174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/events_heimatinfo"}],"about":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/types\/events_heimatinfo"}],"wp:attachment":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/media?parent=9174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}