{"id":9178,"date":"2026-07-14T01:00:11","date_gmt":"2026-07-13T23:00:11","guid":{"rendered":"https:\/\/www.tourismus.dachau.de\/?post_type=events_heimatinfo&#038;p=9178"},"modified":"2026-09-02T01:00:17","modified_gmt":"2026-09-01T23:00:17","slug":"heidi-kirschkern-und-compes-hamburg","status":"publish","type":"events_heimatinfo","link":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/","title":{"rendered":"Heidi \u2013 Kirschkern und Compes\/Hamburg"},"content":{"rendered":"<p>Kirschkern, Compes &amp; Co graj\u0105 Heidi. Ze wszystkim: z szumem jode\u0142 i alpejsk\u0105 po\u015bwiat\u0105, wujkiem z Alm i babciami, fa\u0142szywymi ciotkami i z\u0142ymi guwernantkami oraz kozami, kozami \u2013 ca\u0142\u0105 mas\u0105 k\u00f3z. I oczywi\u015bcie z Piotrkiem z kozami! Jeste\u015bmy w g\u00f3rach, w mie\u015bcie, na hali i w Bad Ragaz. Spacer grani\u0105 po bezdro\u017cach. Niebezpiecznie \u2013 weso\u0142o \u2013 ckliwie \u2013 pasjonuj\u0105co \u2013 powa\u017cnie \u2013 i jak\u017ce pi\u0119knie!<\/p>\n<p>Bilety \u2013 dzieci \/ doro\u015bli: 7 \u20ac<\/p>\n<p>Wej\u015bcie: 15:20, czas trwania: 60 min.<\/p>\n<p>Wiek: Dzieci od 5 lat<\/p>\n<p>Przedsprzeda\u017c:<br \/>\nNaturkostinsel przy M\u00fcnchner Str. 52 w Dachau lub przez internetow\u0105 sprzeda\u017c bilet\u00f3w: ticketino.com<\/p>\n<p>Kontakt:<br \/>\nKleinkunstb\u00fchne Leierkasten Dachau<br \/>\nUhdestr. 2, 85221<\/p>\n<p>Telefon: 08131 \u2013 55195<br \/>\nE-mail: info@leierkasten-dachau.de<br \/>\nStrona g\u0142\u00f3wna: www.leierkasten-dachau.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Kirschkern, Compes &amp; Co spielen Heidi. Mit allem: Mit Tannenrauschen und Alpengl\u00fchen, Alm\u00f6his und Gro\u00dfm\u00fcttern, falschen Tanten und b\u00f6sen Gouvernanten, und Gei\u00dfen, Gei\u00dfen \u2013 ganz vielen Gei\u00dfen. Und nat\u00fcrlich mit dem Gei\u00dfenpeter! Wir sind in den Bergen, in der Stadt, auf der Alm und in Bad Ragaz. Eine Gratwanderung \u00fcber unwegsames Gel\u00e4nde. Gef\u00e4hrlich \u2013 lustig [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-9178","events_heimatinfo","type-events_heimatinfo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Heidi - Kirschkern und Compes\/Hamburg - Dachau Tourismus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heidi - Kirschkern und Compes\/Hamburg - Dachau Tourismus\" \/>\n<meta property=\"og:description\" content=\"Kirschkern, Compes &amp; Co spielen Heidi. Mit allem: Mit Tannenrauschen und Alpengl\u00fchen, Alm\u00f6his und Gro\u00dfm\u00fcttern, falschen Tanten und b\u00f6sen Gouvernanten, und Gei\u00dfen, Gei\u00dfen \u2013 ganz vielen Gei\u00dfen. Und nat\u00fcrlich mit dem Gei\u00dfenpeter! Wir sind in den Bergen, in der Stadt, auf der Alm und in Bad Ragaz. Eine Gratwanderung \u00fcber unwegsames Gel\u00e4nde. Gef\u00e4hrlich \u2013 lustig [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/\" \/>\n<meta property=\"og:site_name\" content=\"Dachau Tourismus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T23:00:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/heidi-kirschkern-und-compes-hamburg\\\/\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/heidi-kirschkern-und-compes-hamburg\\\/\",\"name\":\"Heidi - Kirschkern und Compes\\\/Hamburg - Dachau Tourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\"},\"datePublished\":\"2026-07-13T23:00:11+00:00\",\"dateModified\":\"2026-09-01T23:00:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/heidi-kirschkern-und-compes-hamburg\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/heidi-kirschkern-und-compes-hamburg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/veranstaltungskalender\\\/heidi-kirschkern-und-compes-hamburg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Heidi &#8211; Kirschkern und Compes\\\/Hamburg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"name\":\"Dachau Tourismus\",\"description\":\"Wir freuen uns \u00fcber Ihren Besuch auf unserer Website.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#organization\",\"name\":\"Dachau Tourismus\",\"url\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Dachau Tourismus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tourismus.dachau.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Heidi - Kirschkern und Compes\/Hamburg - Dachau Tourismus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/","og_locale":"pl_PL","og_type":"article","og_title":"Heidi - Kirschkern und Compes\/Hamburg - Dachau Tourismus","og_description":"Kirschkern, Compes &amp; Co spielen Heidi. Mit allem: Mit Tannenrauschen und Alpengl\u00fchen, Alm\u00f6his und Gro\u00dfm\u00fcttern, falschen Tanten und b\u00f6sen Gouvernanten, und Gei\u00dfen, Gei\u00dfen \u2013 ganz vielen Gei\u00dfen. Und nat\u00fcrlich mit dem Gei\u00dfenpeter! Wir sind in den Bergen, in der Stadt, auf der Alm und in Bad Ragaz. Eine Gratwanderung \u00fcber unwegsames Gel\u00e4nde. Gef\u00e4hrlich \u2013 lustig [&hellip;]","og_url":"https:\/\/www.tourismus.dachau.de\/pl\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/","og_site_name":"Dachau Tourismus","article_modified_time":"2026-09-01T23:00:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/","url":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/","name":"Heidi - Kirschkern und Compes\/Hamburg - Dachau Tourismus","isPartOf":{"@id":"https:\/\/www.tourismus.dachau.de\/#website"},"datePublished":"2026-07-13T23:00:11+00:00","dateModified":"2026-09-01T23:00:17+00:00","breadcrumb":{"@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tourismus.dachau.de\/veranstaltungskalender\/heidi-kirschkern-und-compes-hamburg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tourismus.dachau.de\/"},{"@type":"ListItem","position":2,"name":"Heidi &#8211; Kirschkern und Compes\/Hamburg"}]},{"@type":"WebSite","@id":"https:\/\/www.tourismus.dachau.de\/#website","url":"https:\/\/www.tourismus.dachau.de\/","name":"Turystyka w Dachau","description":"Z niecierpliwo\u015bci\u0105 czekamy na Twoj\u0105 wizyt\u0119 na naszej stronie.","publisher":{"@id":"https:\/\/www.tourismus.dachau.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tourismus.dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.tourismus.dachau.de\/#organization","name":"Turystyka w Dachau","url":"https:\/\/www.tourismus.dachau.de\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Dachau Tourismus"},"image":{"@id":"https:\/\/www.tourismus.dachau.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/events_heimatinfo\/9178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/events_heimatinfo"}],"about":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/types\/events_heimatinfo"}],"wp:attachment":[{"href":"https:\/\/www.tourismus.dachau.de\/pl\/wp-json\/wp\/v2\/media?parent=9178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}